{"id":132614,"date":"2024-01-03T15:53:05","date_gmt":"2024-01-03T14:53:05","guid":{"rendered":"https:\/\/namaki.fr\/produit\/tatouage-enfant-monde-des-horreurs-110315\/"},"modified":"2026-03-13T09:06:29","modified_gmt":"2026-03-13T08:06:29","slug":"kindertattoos-horrorwelten","status":"publish","type":"product","link":"https:\/\/namaki.fr\/de\/produit\/tatouage-enfant-monde-des-horreurs\/","title":{"rendered":"Tattoo Kind Horrorwelten"},"content":{"rendered":"<p>Auf der Suche nach dem Detail, das den Unterschied ausmacht? Je nach Verkleidung oder Stimmung k\u00f6nnen Sie die Kindertattoos auf einem Arm, einer Hand oder einem Bein platzieren. Die farbenfrohen Motive wurden von Namaki entworfen, dermatologisch getestet und mit pflanzlichen Tinten formuliert. Sie verleihen der Verkleidung jedes Kindes den letzten Schliff.<\/p>\n<ul>\n<li>Einfach anzuwenden<\/li>\n<li>Gedruckt mit pflanzlichen Tinten<\/li>\n<li>Dermatologisch getestet<\/li>\n<li>Verschiedene Motivgr\u00f6\u00dfen<\/li>\n<li>5 Zusammenstellungen von 2 Abziehb\u00f6gen nach Wahl<\/li>\n<li>Exklusive Illustrationen von Pascale Constantin<\/li>\n<li>Je nach Modell zwischen 7 und 9 Motiven pro Abziehbogen<\/li>\n<li>Zertifizierung CE-Norm Spielzeug<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Sie wollen der Halloween-Verkleidung Ihres Kindes den letzten Schliff verleihen oder sich ganz einfach in Gruselstimmung bringen? Unsere Kindertattoos mit Flederm\u00e4usen, Geistern, Vampiren und Spinnen sorgen f\u00fcr Spa\u00df bei Gro\u00df und Klein!<\/p>","protected":false},"featured_media":132615,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":""},"product_brand":[],"product_cat":[53,34,36,46,57],"product_tag":[],"class_list":{"0":"post-132614","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tatouage-enfant","7":"product_cat-maquillage-deguisement","8":"product_cat-univers-occasions","9":"product_cat-maquillage-halloween","10":"product_cat-tatouages-enfant","11":"pa_certifications-vegan","12":"pa_points-forts-application-simple","13":"pa_points-forts-encres-vegetales","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"gallery_images":[132616,147610,132617,132619,132620,132618],"acf":[],"_links":{"self":[{"href":"https:\/\/namaki.fr\/de\/wp-json\/wp\/v2\/product\/132614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/namaki.fr\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/namaki.fr\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/namaki.fr\/de\/wp-json\/wp\/v2\/comments?post=132614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/namaki.fr\/de\/wp-json\/wp\/v2\/media\/132615"}],"wp:attachment":[{"href":"https:\/\/namaki.fr\/de\/wp-json\/wp\/v2\/media?parent=132614"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/namaki.fr\/de\/wp-json\/wp\/v2\/product_brand?post=132614"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/namaki.fr\/de\/wp-json\/wp\/v2\/product_cat?post=132614"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/namaki.fr\/de\/wp-json\/wp\/v2\/product_tag?post=132614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}